{"id":16,"date":"2020-03-18T16:46:23","date_gmt":"2020-03-18T15:46:23","guid":{"rendered":"https:\/\/www.fair.zone\/?page_id=16"},"modified":"2023-07-26T09:04:18","modified_gmt":"2023-07-26T07:04:18","slug":"partner","status":"publish","type":"page","link":"https:\/\/www.fair.zone\/de\/partner\/","title":{"rendered":"Partner"},"content":{"rendered":"\n<div style=\"height:50px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n              \n                <div class=\"cards-1 v2\">\n                  <div class=\"row\">\n\n                    \n                      <div class=\"col-12 col-sm-6 col-md-3\">\n\n                                                \n                        <a href=\"https:\/\/www.fair.zone\/de\/partner\/fair-rubber\/\" class=\"item\">\n                          <div class=\"image\">\n                            <img decoding=\"async\" src=\"https:\/\/www.fair.zone\/wp-content\/uploads\/2020\/04\/Fairrubber.jpg\" alt=\"Fair Rubber\" \/>\n                          <\/div>\n                          <div class=\"text\">\n                            <h2>Fair Rubber e. V.<\/h2>\n                            <p>Faire Verh\u00e4ltnisse bei Naturkautschuk<\/p>\n                          <\/div>\n                          <div class=\"link\">\n                            <p>Mehr erfahren<\/p>\n                          <\/div>\n                        <\/a>\n\n                        \n                      <\/div>\n\n                    \n                      <div class=\"col-12 col-sm-6 col-md-3\">\n\n                                                \n                        <a href=\"https:\/\/www.fair.zone\/de\/partner\/wlab\/\" class=\"item\">\n                          <div class=\"image\">\n                            <img decoding=\"async\" src=\"https:\/\/www.fair.zone\/wp-content\/uploads\/2020\/04\/wlab.jpg\" alt=\"WLAB-car\" \/>\n                          <\/div>\n                          <div class=\"text\">\n                            <h2>Initiative WLAB<\/h2>\n                            <p>Upcycling auf Sri Lanka in Top-Form<\/p>\n                          <\/div>\n                          <div class=\"link\">\n                            <p>Mehr erfahren<\/p>\n                          <\/div>\n                        <\/a>\n\n                        \n                      <\/div>\n\n                    \n                      <div class=\"col-12 col-sm-6 col-md-3\">\n\n                                                \n                        <a href=\"https:\/\/www.fair.zone\/de\/partner\/fsc\/\" class=\"item\">\n                          <div class=\"image\">\n                            <img decoding=\"async\" src=\"https:\/\/www.fair.zone\/wp-content\/uploads\/2020\/04\/FSC-Logo.jpg\" alt=\"FSC-Logo\" \/>\n                          <\/div>\n                          <div class=\"text\">\n                            <h2>FSC\u00a9 &#8211; nachhaltige Forstwirtschaft<\/h2>\n                            <p>Zertifizierte Quellen f\u00fcr unsere Produktion<\/p>\n                          <\/div>\n                          <div class=\"link\">\n                            <p>Mehr erfahren<\/p>\n                          <\/div>\n                        <\/a>\n\n                        \n                      <\/div>\n\n                    \n                      <div class=\"col-12 col-sm-6 col-md-3\">\n\n                                                \n                        <a href=\"https:\/\/www.fair.zone\/de\/partner\/fair-trade-world-organisation\/\" class=\"item\">\n                          <div class=\"image\">\n                            <img decoding=\"async\" src=\"https:\/\/www.fair.zone\/wp-content\/uploads\/2020\/04\/worldfairtradeorganisation.jpg\" alt=\"World Fair Trade Organisation\" \/>\n                          <\/div>\n                          <div class=\"text\">\n                            <h2>World Fair Trade Organization<\/h2>\n                            <p>Zertifiziert faire Handarbeit<\/p>\n                          <\/div>\n                          <div class=\"link\">\n                            <p>Mehr erfahren<\/p>\n                          <\/div>\n                        <\/a>\n\n                        \n                      <\/div>\n\n                    \n                      <div class=\"col-12 col-sm-6 col-md-3\">\n\n                                                \n                        <a href=\"https:\/\/www.fair.zone\/de\/partner\/rice-carry\/\" class=\"item\">\n                          <div class=\"image\">\n                            <img decoding=\"async\" src=\"https:\/\/www.fair.zone\/wp-content\/uploads\/2020\/10\/partnerbrands.jpg\" alt=\"Partner Brands\" \/>\n                          <\/div>\n                          <div class=\"text\">\n                            <h2>Gemeinsam schaffen wir mehr<\/h2>\n                            <p>Deshalb b\u00fcndeln wir unser Wissen und unterst\u00fctzen uns gegenseitig.<\/p>\n                          <\/div>\n                          <div class=\"link\">\n                            <p>Mehr erfahren<\/p>\n                          <\/div>\n                        <\/a>\n\n                        \n                      <\/div>\n\n                    \n                  <\/div>\n                <\/div>\n\n              ","protected":false},"excerpt":{"rendered":"","protected":false},"author":3,"featured_media":0,"parent":0,"menu_order":4,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"footnotes":""},"class_list":["post-16","page","type-page","status-publish","hentry"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.fair.zone\/de\/wp-json\/wp\/v2\/pages\/16","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.fair.zone\/de\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.fair.zone\/de\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.fair.zone\/de\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.fair.zone\/de\/wp-json\/wp\/v2\/comments?post=16"}],"version-history":[{"count":11,"href":"https:\/\/www.fair.zone\/de\/wp-json\/wp\/v2\/pages\/16\/revisions"}],"predecessor-version":[{"id":5186,"href":"https:\/\/www.fair.zone\/de\/wp-json\/wp\/v2\/pages\/16\/revisions\/5186"}],"wp:attachment":[{"href":"https:\/\/www.fair.zone\/de\/wp-json\/wp\/v2\/media?parent=16"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}